{"id":50,"count":20,"description":"","link":"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/","name":"Business &amp; Entrepreneurship","slug":"business-entrepreneurship","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Business &amp; Entrepreneurship Archives | AFRIDIGITALS ACADEMY BLOG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Business &amp; Entrepreneurship Archives | AFRIDIGITALS ACADEMY BLOG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/\" \/>\n<meta property=\"og:site_name\" content=\"AFRIDIGITALS ACADEMY BLOG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@afridigitalsltd\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/\",\"url\":\"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/\",\"name\":\"Business &amp; Entrepreneurship Archives | AFRIDIGITALS ACADEMY BLOG\",\"isPartOf\":{\"@id\":\"https:\/\/afridigitalsacademy.net\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/afridigitalsacademy.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business &amp; Entrepreneurship\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/afridigitalsacademy.net\/blog\/#website\",\"url\":\"https:\/\/afridigitalsacademy.net\/blog\/\",\"name\":\"AFRIDIGITALS ACADEMY BLOG\",\"description\":\"a leading digital skills training center\",\"publisher\":{\"@id\":\"https:\/\/afridigitalsacademy.net\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/afridigitalsacademy.net\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/afridigitalsacademy.net\/blog\/#organization\",\"name\":\"AFRIDIGITALS ACADEMY BLOG\",\"url\":\"https:\/\/afridigitalsacademy.net\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/afridigitalsacademy.net\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/afridigitalsacademy.net\/blog\/wp-content\/uploads\/2022\/08\/20210424_094732-1024x1024.png\",\"contentUrl\":\"https:\/\/afridigitalsacademy.net\/blog\/wp-content\/uploads\/2022\/08\/20210424_094732-1024x1024.png\",\"width\":1024,\"height\":1024,\"caption\":\"AFRIDIGITALS ACADEMY BLOG\"},\"image\":{\"@id\":\"https:\/\/afridigitalsacademy.net\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/afridigitalsltd\",\"https:\/\/x.com\/afridigitalsltd\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Business &amp; Entrepreneurship Archives | AFRIDIGITALS ACADEMY BLOG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/","og_locale":"en_US","og_type":"article","og_title":"Business &amp; Entrepreneurship Archives | AFRIDIGITALS ACADEMY BLOG","og_url":"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/","og_site_name":"AFRIDIGITALS ACADEMY BLOG","twitter_card":"summary_large_image","twitter_site":"@afridigitalsltd","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/","url":"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/","name":"Business &amp; Entrepreneurship Archives | AFRIDIGITALS ACADEMY BLOG","isPartOf":{"@id":"https:\/\/afridigitalsacademy.net\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/afridigitalsacademy.net\/blog\/category\/business-entrepreneurship\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/afridigitalsacademy.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Business &amp; Entrepreneurship"}]},{"@type":"WebSite","@id":"https:\/\/afridigitalsacademy.net\/blog\/#website","url":"https:\/\/afridigitalsacademy.net\/blog\/","name":"AFRIDIGITALS ACADEMY BLOG","description":"a leading digital skills training center","publisher":{"@id":"https:\/\/afridigitalsacademy.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afridigitalsacademy.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/afridigitalsacademy.net\/blog\/#organization","name":"AFRIDIGITALS ACADEMY BLOG","url":"https:\/\/afridigitalsacademy.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/afridigitalsacademy.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/afridigitalsacademy.net\/blog\/wp-content\/uploads\/2022\/08\/20210424_094732-1024x1024.png","contentUrl":"https:\/\/afridigitalsacademy.net\/blog\/wp-content\/uploads\/2022\/08\/20210424_094732-1024x1024.png","width":1024,"height":1024,"caption":"AFRIDIGITALS ACADEMY BLOG"},"image":{"@id":"https:\/\/afridigitalsacademy.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/afridigitalsltd","https:\/\/x.com\/afridigitalsltd"]}]}},"_links":{"self":[{"href":"https:\/\/afridigitalsacademy.net\/blog\/wp-json\/wp\/v2\/categories\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afridigitalsacademy.net\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/afridigitalsacademy.net\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/afridigitalsacademy.net\/blog\/wp-json\/wp\/v2\/posts?categories=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}